{"id":823,"count":1,"description":"","link":"https:\/\/scroll.media\/en\/tag\/superhuman-en\/","name":"Superhuman","slug":"superhuman-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Superhuman | Scroll.media<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scroll.media\/en\/tag\/superhuman-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Superhuman | Scroll.media\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scroll.media\/en\/tag\/superhuman-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Scroll.media\" \/>\n<meta property=\"og:image\" content=\"https:\/\/scroll.media\/wp-content\/uploads\/2025\/01\/scroll_logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/tag\\\/superhuman-en\\\/\",\"url\":\"https:\\\/\\\/scroll.media\\\/en\\\/tag\\\/superhuman-en\\\/\",\"name\":\"Superhuman | Scroll.media\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/tag\\\/superhuman-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/tag\\\/superhuman-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/scroll.media\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Superhuman\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/scroll.media\\\/en\\\/\",\"name\":\"Scroll.Media\",\"description\":\"\u043d\u043e\u0432\u0438\u043d\u0438 \u0443\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u043e\u0457 tech-\u0456\u043d\u0434\u0443\u0441\u0442\u0440\u0456\u0457\",\"publisher\":{\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/#organization\"},\"alternateName\":\"Scroll Media\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/scroll.media\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/#organization\",\"name\":\"Scroll Media\",\"alternateName\":\"Scroll\",\"url\":\"https:\\\/\\\/scroll.media\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scroll.media\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/scroll_logo.png\",\"contentUrl\":\"https:\\\/\\\/scroll.media\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/scroll_logo.png\",\"width\":1200,\"height\":1200,\"caption\":\"Scroll Media\"},\"image\":{\"@id\":\"https:\\\/\\\/scroll.media\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scrollmediaua\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Superhuman | Scroll.media","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scroll.media\/en\/tag\/superhuman-en\/","og_locale":"en_US","og_type":"article","og_title":"Superhuman | Scroll.media","og_url":"https:\/\/scroll.media\/en\/tag\/superhuman-en\/","og_site_name":"Scroll.media","og_image":[{"width":1200,"height":1200,"url":"https:\/\/scroll.media\/wp-content\/uploads\/2025\/01\/scroll_logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/scroll.media\/en\/tag\/superhuman-en\/","url":"https:\/\/scroll.media\/en\/tag\/superhuman-en\/","name":"Superhuman | Scroll.media","isPartOf":{"@id":"https:\/\/scroll.media\/en\/#website"},"breadcrumb":{"@id":"https:\/\/scroll.media\/en\/tag\/superhuman-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/scroll.media\/en\/tag\/superhuman-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/scroll.media\/en\/"},{"@type":"ListItem","position":2,"name":"Superhuman"}]},{"@type":"WebSite","@id":"https:\/\/scroll.media\/en\/#website","url":"https:\/\/scroll.media\/en\/","name":"Scroll.Media","description":"\u043d\u043e\u0432\u0438\u043d\u0438 \u0443\u043a\u0440\u0430\u0457\u043d\u0441\u044c\u043a\u043e\u0457 tech-\u0456\u043d\u0434\u0443\u0441\u0442\u0440\u0456\u0457","publisher":{"@id":"https:\/\/scroll.media\/en\/#organization"},"alternateName":"Scroll Media","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scroll.media\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/scroll.media\/en\/#organization","name":"Scroll Media","alternateName":"Scroll","url":"https:\/\/scroll.media\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/scroll.media\/en\/#\/schema\/logo\/image\/","url":"https:\/\/scroll.media\/wp-content\/uploads\/2025\/01\/scroll_logo.png","contentUrl":"https:\/\/scroll.media\/wp-content\/uploads\/2025\/01\/scroll_logo.png","width":1200,"height":1200,"caption":"Scroll Media"},"image":{"@id":"https:\/\/scroll.media\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scrollmediaua\/"]}]}},"_links":{"self":[{"href":"https:\/\/scroll.media\/en\/wp-json\/wp\/v2\/tags\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scroll.media\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/scroll.media\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/scroll.media\/en\/wp-json\/wp\/v2\/posts?tags=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}